{"id":245,"date":"2021-12-29T08:47:21","date_gmt":"2021-12-29T08:47:21","guid":{"rendered":"https:\/\/gigroup.draft2017.com\/italia\/?post_type=one-group&#038;p=245"},"modified":"2022-04-20T18:17:41","modified_gmt":"2022-04-20T16:17:41","slug":"formazione","status":"publish","type":"one-group","link":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/","title":{"rendered":"Formazione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"245\" class=\"elementor elementor-245\" data-elementor-post-type=\"one-group\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-259008f header_line_left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"259008f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f9fd6c\" data-id=\"8f9fd6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ce9ca0 elementor-widget elementor-widget-heading\" data-id=\"8ce9ca0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"\/italia\/il-gruppo\/\">Il Gruppo <\/a>- <strong>Formazione<\/strong><\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb7f70f elementor-widget elementor-widget-spacer\" data-id=\"cb7f70f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e4748f elementor-widget elementor-widget-heading\" data-id=\"8e4748f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Gi Formazione<br \/>\n<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c29a0d elementor-widget elementor-widget-spacer\" data-id=\"2c29a0d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c791f6c elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c791f6c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-24a7559\" data-id=\"24a7559\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7b8f02 mobile_img_max_height_50 elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-image\" data-id=\"f7b8f02\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"305\" height=\"94\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/03\/formazione-white-.png\" class=\"attachment-full size-full wp-image-5373\" alt=\"\" srcset=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/03\/formazione-white-.png 305w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/03\/formazione-white--300x92.png 300w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-340c87c elementor-icon-list--layout-inline elementor-align-right one_group_socials elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"340c87c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/company\/gi-group\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd6cf40 elementor-section-full_width one_group_container elementor-section-height-default elementor-section-height-default\" data-id=\"cd6cf40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6c4b90\" data-id=\"b6c4b90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f22be8 elementor-section-full_width elements_max_width_1065 elementor-section-height-default elementor-section-height-default\" data-id=\"3f22be8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-88ab3e0\" data-id=\"88ab3e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce3b94f onegroup-h2  elementor-widget elementor-widget-heading\" data-id=\"ce3b94f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione&nbsp;per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe4eab7 elementor-widget elementor-widget-spacer\" data-id=\"fe4eab7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d46be7 elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"0d46be7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b7e21a3\" data-id=\"b7e21a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fde8777 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"fde8777\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tMettiamo a disposizione il know-how del nostro team per offrirti un servizio di outsourcing non solo preciso e puntuale nel rispetto delle scadenze, ma proiettato al futuro e alle necessit\u00e0 che emergeranno per il tuo business e per le tue persone.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4a65c9 elementor-widget elementor-widget-spacer\" data-id=\"f4a65c9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58590bf elementor-widget elementor-widget-button\" data-id=\"58590bf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.gigroup.it\/aziende\/servizi\/formazione\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri Gi Formazione<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b26038f elementor-widget elementor-widget-spacer\" data-id=\"b26038f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f29975\" data-id=\"3f29975\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-576d4fb single_one_group_image mobile_image_line mobile_line_cyan tablet_line elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"576d4fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"945\" height=\"646\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/giformazione-holding.jpg\" class=\"attachment-full size-full wp-image-11060\" alt=\"\" srcset=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/giformazione-holding.jpg 945w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/giformazione-holding-300x205.jpg 300w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/giformazione-holding-768x525.jpg 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d58bbcc one_group_container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d58bbcc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed11cbb\" data-id=\"ed11cbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-edc3d7a elementor-section-full_width elements_max_width_1065 mobile_accordion elementor-section-height-default elementor-section-height-default\" data-id=\"edc3d7a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7fd6c6f\" data-id=\"7fd6c6f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed28f6f main_header_accordion elementor-widget elementor-widget-heading\" data-id=\"ed28f6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il nostro approccio<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d803829 elementor-widget elementor-widget-spacer\" data-id=\"d803829\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c64dfe1 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"c64dfe1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Attraverso la leva dell\u2019education<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b210a elementor-widget elementor-widget-text-editor\" data-id=\"46b210a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Attraverso la leva dell\u2019education and training vogliamo contribuire alla generazione di competenze finalizzate al placement e alla performance delle persone, mettendoci a servizio di aziende e candidati.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc9e80 elementor-widget elementor-widget-spacer\" data-id=\"8bc9e80\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bffd169 elementor-widget elementor-widget-spacer\" data-id=\"bffd169\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c96b8dd main_header_accordion elementor-widget elementor-widget-heading\" data-id=\"c96b8dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le soluzioni<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2568c12 elementor-widget elementor-widget-spacer\" data-id=\"2568c12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a533253 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"a533253\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Formazione <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-812fdc4 elementor-widget elementor-widget-text-editor\" data-id=\"812fdc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u2022 Formazione Base<br \/>\u2022 Formazione on the job<br \/>\u2022 Formazione professionale<br \/>\u2022 Corsi sulla sicurezza<br \/>\u2022 Academy<br \/>\u2022 ITS E IFTS<br \/>\u2022 Diritto Mirato<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e979ebd elementor-widget elementor-widget-spacer\" data-id=\"e979ebd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2938238 elementor-widget elementor-widget-spacer\" data-id=\"2938238\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e89724 elementor-widget elementor-widget-spacer\" data-id=\"2e89724\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99e953c one_group_container mobile_no_side_margin elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"99e953c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19255fa\" data-id=\"19255fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-adff525 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"adff525\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d9309ad\" data-id=\"d9309ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28d846b elementor-widget elementor-widget-heading\" data-id=\"28d846b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/italia\/il-gruppo\/#glialtribrand\">Gi Group Holding in Italia<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dffed88 elementor-widget elementor-widget-button\" data-id=\"dffed88\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri gli altri brand<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b8322 elementor-widget elementor-widget-spacer\" data-id=\"e0b8322\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9acfe9e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-shortcode\" data-id=\"9acfe9e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">    <div id=\"brand_cards\" class=\"brands_cards_holder container-fluid\">\n      <div class=\"row px-0\">\n                                      <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 300\">\n            <div id=\"brand_card_248\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/intooo-h.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Con 30 anni di esperienza in Italia, UK, Irlanda e USA, INTOO aiuta aziende e persone a comprendere e affrontare il cambiamento. \nLavoriamo sull'employability dell'individuo per supportarne la continuit\u00e0 professionale dentro l'azienda e nel mercato del lavoro, durante tutto l'arco della sua vita lavorativa.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/transizione-e-sviluppo-di-carriera\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 299\">\n            <div id=\"brand_card_243\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/odm-150.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Specialisti nei sistemi di gestione delle risorse umane.\nIn ODM Consulting lavoriamo per trasformare in performance il potenziale delle persone, ingaggiarle, riconoscerne il contributo e migliorare l\u2019organizzazione.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/consulenza-hr\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 298\">\n            <div id=\"brand_card_239\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/gi-hr.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi HR Services \u00e8 la societ\u00e0 specializzata in servizi di outsourcing a supporto dell\u2019amministrazione e gestione del personale.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/amministrazione-hr\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 297\">\n            <div id=\"brand_card_241\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/tacktmi-1.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Attraverso design e tecnologie all'avanguiardia, Tack TMI crea degli interventi formativi efficaci e dall'impatto reale e duraturo. La nostra gamma di servizi si basa su oltre 110 anni di esperienza e ci permette di collaborare con i clienti per fornire soluzioni di apprendimento scalabili, flessibili e globali.  <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione-e-sviluppo\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 296\">\n            <div id=\"brand_card_245\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi Formazione si occupa di organizzare corsi di consulenza formativa e di formazione\u00a0per i lavoratori in somministrazione e candidati a missione\u00a0di somministrazione.<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 295\">\n            <div id=\"brand_card_235\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/GI-BPO-_-LOGO-POSITIVE.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi BPO \u00e8 la societ\u00e0 specializzata nel campo dell'esternalizzazione dei processi operativi e delle trasformazioni aziendali.<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/operations-supply-chain\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#f8fb63\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#f8fb63\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 294\">\n            <div id=\"brand_card_233\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/enginium-colors-300.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Enginium \u00e8 la societ\u00e0 specializzata in servizi di consulenza tecnologica. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/technology-consulting\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 293\">\n            <div id=\"brand_card_232\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/C2C-blue-180px.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">C2C \u00e8 la societ\u00e0 di sales e field marketing di Gi Group Holding. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/sales-field-marketing\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 292\">\n            <div id=\"brand_card_231\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/exs-colors-180.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">EXS si occupa dei servizi dedicati al mondo Executive. \nSupportiamo l\u2019evoluzione e la trasformazione dell\u2019Executive Selection integrandola con gli sviluppi scientifici e le evoluzioni digitali. \n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/executive-selection\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 291\">\n            <div id=\"brand_card_229\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/03\/wuser.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Wyser si occupa di ricerca e selezione di profili di middle e senior management. \nCollaboriamo con professionisti di talento per supportarli nello sviluppo della loro professionalit\u00e0 e della loro carriera. Affianchiamo le aziende a sviluppare il loro business.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/ricerca-e-selezione\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 290\">\n            <div id=\"brand_card_159\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi Group \u00e8 la prima agenzia per il lavoro italiana con oltre 500 filiali nel mondo e una gamma completa di servizi HR. Offre soluzioni di Temporary, Permanent e Professional Staffing pensate per le esigenze di piccole e medie imprese, aziende corporate e multinazionali per le quali il Gruppo ha sviluppato uno specifico know how. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/temporary-permanent-e-professional-staffing\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#96b9ff\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#96b9ff\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                        <\/div>\n    <\/div>\n    <script>\n      jQuery(document).ready(function($) {\n        function owlInitialize() {\n            if ($(window).width() < 1025) {\n                $('#brand_cards .row').addClass(\"owl-carousel\");\n                $('#brand_cards .owl-carousel').owlCarousel({\n                    loop:false,    \n                    margin: 20,  \n                    nav: false,\n                    dots: true,        \n                    responsive:{\n                        0:{\n                            items:1,           \n                        },\n                        640:{\n                            items:1,           \n                        }, \n                    }\n                });\n            }else{\n                $('.owl-carousel').owlCarousel('destroy');\n                $('#brand_cards .row').removeClass(\"owl-carousel\");\n            }\n        }\n      \n        owlInitialize();\n\n        jQuery(window).resize(function() {\n          owlInitialize();\n        });\n      });\n    <\/script>\n    <style>\n      @media(max-width: 1024px) {\n        #brand_cards {\n          padding-bottom: 80px;\n        }\n        #brand_cards .owl-dots {\n          display: flex;\n          justify-content: center;\n          margin-top: 40px;\n        }\n        #brand_cards .owl-stage-outer {\n          overflow: visible;\n        }\n        #brand_cards .brand_card_holder {\n          overflow-y: auto;\n        }\n        #brand_cards .brand_card_inner {\n          margin: 0 15px;\n        }\n        #brand_cards .brand_card_holder {\n          border-radius: 8px;\n        }\n        #brand_cards .brand_card_content {\n          height: 190px;\n          overflow: hidden;\n          margin-bottom: 30px;\n        }\n        .brand_card_thumb img {\n          height: 65px;\n          object-fit: contain;\n        }\n        #brand_cards .owl-dot {\n          width: 12px;\n          height: 12px;\n          background-color: #ECE9F1;\n          margin: 0px 5px;\n          border-style: none;\n        }\n        #brand_cards .owl-dot.active {\n          width: 12px;\n          height: 12px;\n          background-color: #005AFF;\n        }\n        #brand_cards .brand_card_inner {\n          width: 100%;\n        }\n      }\n      @media(min-width: 769px) and (max-width: 1024px) {\n        #brand_cards .brand_card_content {\n          height: 110px;\n        }\n      }\n    <\/style>\n  <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gi Formazione si occupa di organizzare corsi di consulenza formativa e di formazione\u00a0per i lavoratori in somministrazione e candidati a missione\u00a0di somministrazione.<\/p>\n","protected":false},"featured_media":859,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"country":[],"class_list":["post-245","one-group","type-one-group","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una propostaHR completa<\/title>\n<meta name=\"description\" content=\"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gi Group Holding - Formazione\" \/>\n<meta property=\"og:description\" content=\"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Gi Group Holding Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T16:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gi Group Holding - Formazione\" \/>\n<meta name=\"twitter:description\" content=\"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\",\"name\":\"Una propostaHR completa\",\"isPartOf\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png\",\"datePublished\":\"2021-12-29T08:47:21+00:00\",\"dateModified\":\"2022-04-20T16:17:41+00:00\",\"description\":\"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png\",\"contentUrl\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png\",\"width\":276,\"height\":80},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Il Gruppo\",\"item\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/#website\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/\",\"name\":\"Gi Group Holding Italia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gigroupholding.com\/italia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una propostaHR completa","description":"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/","og_locale":"it_IT","og_type":"article","og_title":"Gi Group Holding - Formazione","og_description":"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline.","og_url":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/","og_site_name":"Gi Group Holding Italia","article_modified_time":"2022-04-20T16:17:41+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Gi Group Holding - Formazione","twitter_description":"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline.","twitter_image":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/","url":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/","name":"Una propostaHR completa","isPartOf":{"@id":"https:\/\/www.gigroupholding.com\/italia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage"},"image":{"@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png","datePublished":"2021-12-29T08:47:21+00:00","dateModified":"2022-04-20T16:17:41+00:00","description":"Gi Formazione \u00e8 la societ\u00e0 del Gruppo che si occupa di consulenza formativa e di corsi di formazione per i lavoratori in somministrazione e candidati, dedicando particolare attenzione alla ricerca di fornitori qualificati ed enti specializzati nelle diverse discipline","breadcrumb":{"@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#primaryimage","url":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png","contentUrl":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png","width":276,"height":80},{"@type":"BreadcrumbList","@id":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Il Gruppo","item":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/"},{"@type":"ListItem","position":2,"name":"Formazione"}]},{"@type":"WebSite","@id":"https:\/\/www.gigroupholding.com\/italia\/#website","url":"https:\/\/www.gigroupholding.com\/italia\/","name":"Gi Group Holding Italia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gigroupholding.com\/italia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group"}],"about":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/types\/one-group"}],"version-history":[{"count":86,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/245\/revisions"}],"predecessor-version":[{"id":11741,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/245\/revisions\/11741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/media\/859"}],"wp:attachment":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/country?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}