{"id":159,"date":"2021-12-28T15:12:24","date_gmt":"2021-12-28T15:12:24","guid":{"rendered":"https:\/\/gigroup.draft2017.com\/italia\/?post_type=one-group&#038;p=159"},"modified":"2026-05-05T11:16:03","modified_gmt":"2026-05-05T09:16:03","slug":"temporary-permanent-e-professional-staffing","status":"publish","type":"one-group","link":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/temporary-permanent-e-professional-staffing\/","title":{"rendered":"Temporary, Permanent e Professional Staffing"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"159\" class=\"elementor elementor-159\" data-elementor-post-type=\"one-group\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2732e9 header_line_left elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2732e9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8447969\" data-id=\"8447969\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8c1957 elementor-widget elementor-widget-heading\" data-id=\"a8c1957\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"\/italia\/il-gruppo\/\">Il Gruppo <\/a> -  <strong>Temporary, Permanent e Professional Staffing<\/strong><\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3224491 elementor-widget elementor-widget-spacer\" data-id=\"3224491\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca7e0f8 elementor-widget elementor-widget-heading\" data-id=\"ca7e0f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Temporary, Permanent  &amp; <br \/>\nProfessional Staffing <\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac499a elementor-widget elementor-widget-spacer\" data-id=\"2ac499a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-568baf6 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"568baf6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-862229f\" data-id=\"862229f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b6a38b mobile_img_max_height_50 elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-image\" data-id=\"8b6a38b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"218\" height=\"86\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-negativo-monocromatico.png\" class=\"attachment-full size-full wp-image-1915\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f9796e elementor-icon-list--layout-inline elementor-align-right one_group_socials elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7f9796e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/company\/gi-group\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a537588 elementor-section-full_width one_group_container elementor-section-height-default elementor-section-height-default\" data-id=\"a537588\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b2c9db\" data-id=\"7b2c9db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-36fc47d elementor-section-full_width elements_max_width_1065 elementor-section-height-default elementor-section-height-default\" data-id=\"36fc47d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0ff6fa8\" data-id=\"0ff6fa8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e79ee1b onegroup-h2 elementor-widget elementor-widget-heading\" data-id=\"e79ee1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">L'attivit\u00e0 di Temporary, Permanent e Professional Staffing \u00e8 il core business del Gruppo, ed \u00e8 portata avanti attraverso il brand Gi Group.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb4784 elementor-widget elementor-widget-spacer\" data-id=\"cfb4784\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b22a0c elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"4b22a0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d1c400a\" data-id=\"d1c400a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c79b50b elementor-widget elementor-widget-text-editor\" data-id=\"c79b50b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Siamo la pi\u00f9 grande agenzia per il lavoro italiana presente su tutto il territorio nazionale con oltre 200 filiali (oltre 500 in tutto il mondo) e una gamma completa di servizi HR.<br \/>Il nostro DNA italiano ci permette di essere flessibili, creativi e trovare le soluzioni pi\u00f9 adatte in tempi rapidi. <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adb9557 elementor-widget elementor-widget-text-editor\" data-id=\"adb9557\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il nostro essere globali ci permette di attingere dalle best practice dei paesi in cui siamo presenti per offrire un servizio sempre migliore.<\/p><p>Crediamo nella centralit\u00e0 della persona e nella sua dignit\u00e0: la certificazione etica SA8000 rafforza il nostro impegno nell\u2019affrontare il lavoro di ogni giorno in modo socialmente responsabile.<\/p><p>La presenza capillare su tutto il territorio nazionale ci permette di essere vicini ai bisogni delle piccole e medie imprese; allo stesso tempo, grazie ad una struttura corporate organizzata in divisioni specializzate, abbiamo il know how necessario per accompagnare l\u2019evoluzione di grandi realt\u00e0 nazionali e multinazionali.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ebdcfd elementor-widget elementor-widget-button\" data-id=\"5ebdcfd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.gigroup.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri Gi Group <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeddd63 elementor-widget elementor-widget-spacer\" data-id=\"eeddd63\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e6feb8a\" data-id=\"e6feb8a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b619e4 single_one_group_image mobile_image_line mobile_line_cyan tablet_line elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"2b619e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1083\" height=\"814\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/IMAGE_GIGROUP@2x-1.jpg\" class=\"attachment-full size-full wp-image-4297\" alt=\"\" srcset=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/IMAGE_GIGROUP@2x-1.jpg 1083w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/IMAGE_GIGROUP@2x-1-300x225.jpg 300w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/IMAGE_GIGROUP@2x-1-1024x770.jpg 1024w, https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/IMAGE_GIGROUP@2x-1-768x577.jpg 768w\" sizes=\"(max-width: 1083px) 100vw, 1083px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8418b3a one_group_container elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8418b3a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaa6635\" data-id=\"eaa6635\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-976a53f elementor-section-full_width elements_max_width_1065 mobile_accordion elementor-section-height-default elementor-section-height-default\" data-id=\"976a53f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-19111ec\" data-id=\"19111ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38a3cd6 main_header_accordion elementor-widget elementor-widget-heading\" data-id=\"38a3cd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il nostro approccio<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d371c elementor-widget elementor-widget-spacer\" data-id=\"c2d371c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afe272a elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"afe272a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ogni giorno, in tutti i paesi<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ce4d9 elementor-widget elementor-widget-text-editor\" data-id=\"a6ce4d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ogni giorno, in tutti i paesi in cui siamo presenti, ascoltiamo i bisogni sempre pi\u00f9 complessi di aziende e persone, con un unico obiettivo: creare valore.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfad19a elementor-widget elementor-widget-spacer\" data-id=\"dfad19a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a11bec elementor-widget elementor-widget-heading\" data-id=\"1a11bec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tra i punti di forza:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba612af elementor-widget elementor-widget-text-editor\" data-id=\"ba612af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><br \/>&#8211; le nostre persone<br \/>&#8211; partnership<br \/>&#8211; conoscenza del mercato locale e globale<br \/>&#8211; competenza nel recruitment e nella gestione della forza lavoro<br \/>&#8211; specializzazione in determinati settori e profili<br \/>&#8211; analisi dei bisogni e progettazione di soluzioni<br \/>&#8211; approccio One Contact &amp; One Project<br \/>&#8211; processi efficienti e conformi<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77a2d3a elementor-widget elementor-widget-spacer\" data-id=\"77a2d3a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c06a961 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"c06a961\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conoscenza del mercato del lavoro locale e internazionale:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1cc8aa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"e1cc8aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tForti della nostra conoscenza del mercato del lavoro locale e internazionale, siamo in grado di soddisfare le esigenze delle aziende internazionali e delle piccole e medie imprese.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d77577 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"9d77577\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8e2ad6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"c8e2ad6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Competenza nel recruitment e nella gestione della forza lavoro:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3efcead elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"3efcead\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t ci avvaliamo di team specializzati nella ricerca, nel coinvolgimento e nella selezione dei candidati, cos\u00ec come nella gestione, soddisfazione e mantenimento dei dipendenti, trattando ogni candidato o dipendente in conformit\u00e0 con i nostri valori e il nostro codice etico.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a071baa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"a071baa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5a114 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3b5a114\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Specializzazioni in determinati settori e profili:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db9330 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"1db9330\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tI nostri team sono esperti in determinati settori e in specifiche tipologie di profili dei candidati.  Le nostre specializzazioni e l&#8217;approfondita conoscenza del settore ci permettono di comprendere pienamente le esigenze di clienti e candidati e di fornire servizi e soluzioni ad alto valore aggiunto. Queste conoscenze specialistiche sono la base su cui costruiamo la fiducia e la collaborazione con i clienti.\u00a0\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1683406 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"1683406\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b3078 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"c8b3078\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Analisi dei bisogni e progettazione di soluzioni:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c887b6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"6c887b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tAbbiamo creato una variet\u00e0 di modelli di servizi e soluzioni scalabili e integrate ricorrendo alla nostra esperienza e competenza per meglio comprendere le esigenze dei clienti, facendo in modo che la nostra proposta di servizio rifletta e soddisfi pienamente le loro richieste.  \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9799ba6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"9799ba6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed1e70 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"7ed1e70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Approccio One Contact &amp; One Project:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6cafc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"0d6cafc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tGestiamo progetti complessi offrendo soluzioni innovative e flessibili, occupandoci di una sola o di tutte le sedi del cliente all&#8217;interno di una regione, di un Paese o di tutte le sedi globali. Assegniamo un contatto, che rappresenta il team di account management nazionale e internazionale, a ogni sede del cliente e consideriamo ogni sfida locale come un progetto. \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18bfbed elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"18bfbed\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d615598 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"d615598\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Processi efficienti e conformi: <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8d82ae elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b8d82ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tMonitoriamo attentamente tutti i processi garantendo compliance e standard a livello nazionale o internazionale, concentrandoci sul miglioramento continuo per garantire efficienza ed efficacia, ricorrendo all&#8217;uso di tecnologia innovativa. \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fba1212 elementor-widget elementor-widget-spacer\" data-id=\"fba1212\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11ac50a main_header_accordion elementor-widget elementor-widget-heading\" data-id=\"11ac50a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le soluzioni<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e190321 elementor-widget elementor-widget-spacer\" data-id=\"e190321\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39ad359 elementor-widget elementor-widget-toggle\" data-id=\"39ad359\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6041\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Temporary Staffing<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6041\"><p>Con il servizio di Temporary Staffing ti garantiamo flessibilit\u00e0 contrattuale, efficacia, efficienza e un monitoraggio dei costi.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9539dd5 elementor-widget elementor-widget-toggle\" data-id=\"9539dd5\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Permanent <\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1561\">Con un approccio consulenziale offriamo soluzioni per la gestione di progetti mirati alla ricerca di profili da inserire direttamente nella tua azienda. Il nostro processo di ricerca e selezione ha una prerogativa: pu\u00f2 contare su servizi modulabili in base alle specifiche esigenze della tua realt\u00e0, in tutte le fasi del processo.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380bad8 elementor-widget elementor-widget-toggle\" data-id=\"380bad8\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-5871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Professional Staffing<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5871\">Grazie ad una struttura dedicata e ad una metodologia che mira a trasformare le competenze e il potenziale dei Candidati in percorsi professionali di successo, soddisfiamo le esigenze di profili specializzati delle aziende.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d07f18 elementor-widget elementor-widget-toggle\" data-id=\"1d07f18\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-3041\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">SMS \u2013 Site Managed Services:<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3041\">Con SMS (Site Managed Services) siamo in grado di gestire i tuoi fabbisogni di flessibilit\u00e0 direttamente nei siti produttivi, consentendoti di concentrarti sulle tue attivit\u00e0 core.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fab10fb elementor-widget elementor-widget-toggle\" data-id=\"fab10fb\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2621\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2621\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">MSM - Multi-Site Management<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2621\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2621\"><p>Quando le esigenze di flessibilit\u00e0 dei clienti riguardano un certo numero di siti in una regione specifica, un unico esperto dedicato di Gi Group o un team responsabile si occuper\u00e0 centralmente di gestire le necessit\u00e0 in tutti i siti.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b03c673 elementor-widget elementor-widget-toggle\" data-id=\"b03c673\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1841\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1841\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">RPO - Recruitment Process Outsourcing<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1841\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1841\">Con RPO, Recruitment Process Outsourcing,approfondiamo la nostra analisi con l\u2019obiettivo di identificare le competenze, le risorse, il processo e gli strumenti pi\u00f9 adatti e garantendo alla tua azienda il minor effort possibile.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74589b2 elementor-widget elementor-widget-toggle\" data-id=\"74589b2\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Assessment Center<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1211\"><p>Attraverso il nostro Assessment Center puoi accedere ad un processo standardizzato, approfondito, oggettivo e valido di valutazione delle competenze. Si tratta di una metodologia predittiva che consente di inserire le persone pi\u00f9 adatte alle esigenze e al contesto e che garantisce una migliore performance del Candidato.<\/p><p>Tirocini Attraverso il nostro Servizio Tirocini promuoviamo esperienze in azienda finalizzate a favorire l\u2019inserimento lavorativo e ad affinare l\u2019apprendimento e la formazione di talenti.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-295716b elementor-widget elementor-widget-toggle\" data-id=\"295716b\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-4331\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">StartApp 2.0<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4331\">\u00c8 il servizio per l\u2019attivazione dell\u2019apprendistato professionalizzante. Con StartApp 2.0 ti mettiamo a disposizione tutto il nostro know how per supportarti nelle diverse fasi.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0689331 elementor-widget elementor-widget-toggle\" data-id=\"0689331\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Academy<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6851\">Academy \u00e8 un processo integrato composto da attraction, qualification, formazione \ne gestione di risorse \ufb01nalizzato all\u2019inserimento in azienda di pro\ufb01li specializzati. <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f22a0 elementor-widget elementor-widget-toggle\" data-id=\"75f22a0\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">MoveUp<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1231\">Il nostro servizio creato per rispondere al tuo bisogno di figure professionali difficilmente reperibili sul tuo territorio. Promuoviamo e rendiamo pi\u00f9 semplice la mobilit\u00e0 nazionale e internazionale delle risorse.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82d4996 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-toggle\" data-id=\"82d4996\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1371\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1371\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Tirocini<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1371\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1371\">Attraverso il nostro Servizio Tirocini promuoviamo esperienze in azienda finalizzate a favorire l\u2019inserimento lavorativo e ad affinare l\u2019apprendimento e la formazione di talenti.\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c08d44 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-toggle\" data-id=\"5c08d44\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-times\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Employer Branding<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9651\">Con il servizio di Employer Branding costruiamo una strategia che ti permette l\u2019attraction e la \ufb01delizzazione dei potenziali talenti. Evidenziamo la qualit\u00e0 ed i plus del tuo brand e della tua Azienda come luogo ideale di lavoro. Costruiamo un\u2019efficace strategia di\ncomunicazione.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-799b354 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"799b354\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SMS \u2013 Site Managed Services<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97d0196 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"97d0196\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Looking for flexible staff on specific sites? Our SMS solution is the answer. This exclusive service model is tailored to become an integral and flexible part of your organisation. Designed to manage high volumes of temporary workers, it focuses on efficient planning and workforce management, and is built to enhance quality and flexibility.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71d2ef3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"71d2ef3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35b257a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"35b257a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MSM - Multi-Site Management <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b88e5ff elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b88e5ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>When your needs of flexibility are split across a number of sites in a defined region, one central dedicated Gi Group expert or team responsible takes care of managing your staffing necessities at all site.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c42e90 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"0c42e90\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb73b49 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"fb73b49\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MoveUP<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c1fa1b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"2c1fa1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tOur solution to satisfy your staffing needs, even in situations where skilled candidates are difficult to find in a specific local labour market. Leveraging our internal expertise and network, we provide a 360\u00b0 service: from the identification of potential candidates abroad, to their attraction and selection, management of visa, travel and accommodation, welcoming, onboarding and taking care of them on arrival and beyond. Compliance with international and national rules and regulations, and respect of people according to our group\u2019s Values and Code of Ethics are our main concern.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c333702 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"c333702\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66994f1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"66994f1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Master Vendor<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c4b9e5 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"8c4b9e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tOur Master Vendor solutions guarantee the reliable, flexible, qualitative and in-time fulfilment of your staffing needs, while at the same time reducing your administrative efforts. Coordinating with other suppliers as co-partners, we are your single point of contact, fully involved in the service delivery and responsible for service quality and performance.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1048cff elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"1048cff\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f21236d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"f21236d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">COD \u2013 Central Order Desk<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c97b425 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"c97b425\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t With one single point of contact, we ensure the central management of all orders across multiple sites, increasing process and communication efficiency, guaranteeing transparency and cost control, and allowing close management of delivery performance.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81d4217 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"81d4217\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c9945 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"63c9945\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Volume Hiring<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4a220a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b4a220a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tFor those situations where you need to find and onboard high numbers of people within clearly defined timeframes (short period of time or where there is a constantly high demand for resources). We unburden you from the effort it takes to satisfy these needs, taking care of an accurate planning of media investments for candidate attraction, managing reliable candidate engagement, qualification, selection, hiring and onboarding according to the agreed criteria and timelines, and providing transparency on ongoing processes through precise reporting and regular status updates.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfd1343 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"cfd1343\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b6605c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"9b6605c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">RPO - Recruitment Process Outsourcing <\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8de97fb elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"8de97fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t&#8211; An end-to-end management of all your recruitment activities (or some of them) performed by dedicated recruitment experts allows your organisation to optimise productivity, gain efficiency and focus on core business. Integrating with your own technology, methodologies and reporting, we assume ownership of the design and delivery of the recruitment process with full responsibility on results.\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d87dd39 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"d87dd39\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff90ed elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3ff90ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Professional Training<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5fc4f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"9c5fc4f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t When you need to skill, upskill or reskill your candidates and workforce, our staffing-related training solution, based on six pillars (Career guidance, Basic Training Education, Health &#038; Safety, Academy, Training-on-the-job, Continuous Learning) helps generating the competences that your organisation need, in order to benefit from up-to-date and prepared people, \n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc274f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"dbc274f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b590e7e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b590e7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Employer Branding<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a9027e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"9a9027e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t When you need brand awareness and brand reputation at an efficient cost, we are at your side to position your company as an employer of choice, by designing, executing and monitoring a structured attraction plan (including communication and media planning activities in co-branding via web\/social media campaigns as well as offline campaigns &#038; PR), in order to catch, connect with and retain the top talents in the labour market.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-449443e elementor-widget elementor-widget-spacer\" data-id=\"449443e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6306945 one_group_container mobile_no_side_margin elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"6306945\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67ca83e\" data-id=\"67ca83e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ed9305 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ed9305\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-230fa6d\" data-id=\"230fa6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb3bd24 elementor-widget elementor-widget-spacer\" data-id=\"eb3bd24\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0a6dcb one_group_container mobile_no_side_margin elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f0a6dcb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a25a304\" data-id=\"a25a304\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-115c668 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"115c668\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6204c1a\" data-id=\"6204c1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b448c9b elementor-widget elementor-widget-heading\" data-id=\"b448c9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gi Group Holding in Italia<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1349956 elementor-widget elementor-widget-button\" data-id=\"1349956\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopri gli altri brand<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf8df9 elementor-widget elementor-widget-spacer\" data-id=\"5cf8df9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7bee0b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-shortcode\" data-id=\"f7bee0b\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">    <div id=\"brand_cards\" class=\"brands_cards_holder container-fluid\">\n      <div class=\"row px-0\">\n                                      <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 300\">\n            <div id=\"brand_card_248\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/intooo-h.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Con 30 anni di esperienza in Italia, UK, Irlanda e USA, INTOO aiuta aziende e persone a comprendere e affrontare il cambiamento. \nLavoriamo sull'employability dell'individuo per supportarne la continuit\u00e0 professionale dentro l'azienda e nel mercato del lavoro, durante tutto l'arco della sua vita lavorativa.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/transizione-e-sviluppo-di-carriera\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 299\">\n            <div id=\"brand_card_243\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/odm-150.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Specialisti nei sistemi di gestione delle risorse umane.\nIn ODM Consulting lavoriamo per trasformare in performance il potenziale delle persone, ingaggiarle, riconoscerne il contributo e migliorare l\u2019organizzazione.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/consulenza-hr\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 298\">\n            <div id=\"brand_card_239\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/gi-hr.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi HR Services \u00e8 la societ\u00e0 specializzata in servizi di outsourcing a supporto dell\u2019amministrazione e gestione del personale.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/amministrazione-hr\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 297\">\n            <div id=\"brand_card_241\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/tacktmi-1.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Attraverso design e tecnologie all'avanguiardia, Tack TMI crea degli interventi formativi efficaci e dall'impatto reale e duraturo. La nostra gamma di servizi si basa su oltre 110 anni di esperienza e ci permette di collaborare con i clienti per fornire soluzioni di apprendimento scalabili, flessibili e globali.  <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione-e-sviluppo\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 296\">\n            <div id=\"brand_card_245\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/A_MGFjZjlkZDY2YjhlM2JmOTwIVUCwKQUCla5wJnu2e3g8K2h32eqLHQ19OWY1bEW2rZ8564Latqd65c8m_5KLncrnSWi_Ux8kargQp3HFSg1b1CMHLDpnBpXURfd6hF21.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi Formazione si occupa di organizzare corsi di consulenza formativa e di formazione\u00a0per i lavoratori in somministrazione e candidati a missione\u00a0di somministrazione.<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/formazione\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 295\">\n            <div id=\"brand_card_235\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/GI-BPO-_-LOGO-POSITIVE.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi BPO \u00e8 la societ\u00e0 specializzata nel campo dell'esternalizzazione dei processi operativi e delle trasformazioni aziendali.<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/operations-supply-chain\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#f8fb63\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#f8fb63\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 294\">\n            <div id=\"brand_card_233\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/enginium-colors-300.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Enginium \u00e8 la societ\u00e0 specializzata in servizi di consulenza tecnologica. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/technology-consulting\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 293\">\n            <div id=\"brand_card_232\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/C2C-blue-180px.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">C2C \u00e8 la societ\u00e0 di sales e field marketing di Gi Group Holding. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/sales-field-marketing\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 292\">\n            <div id=\"brand_card_231\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/exs-colors-180.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">EXS si occupa dei servizi dedicati al mondo Executive. \nSupportiamo l\u2019evoluzione e la trasformazione dell\u2019Executive Selection integrandola con gli sviluppi scientifici e le evoluzioni digitali. \n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/executive-selection\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 291\">\n            <div id=\"brand_card_229\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/03\/wuser.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Wyser si occupa di ricerca e selezione di profili di middle e senior management. \nCollaboriamo con professionisti di talento per supportarli nello sviluppo della loro professionalit\u00e0 e della loro carriera. Affianchiamo le aziende a sviluppare il loro business.\n<\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/ricerca-e-selezione\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#00145a\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#00145a\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                                                <div class=\"brand_card_inner col-lg-4 px-0\" style=\"z-index: 290\">\n            <div id=\"brand_card_159\" class=\"brand_card_holder d-flex flex-column justify-content-between\">\n              <div class=\"brand_card_thumb\"><img decoding=\"async\" src=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png\" alt=\"Post thumbnail\"><\/div>\n              <div class=\"brand_card_content\">Gi Group \u00e8 la prima agenzia per il lavoro italiana con oltre 500 filiali nel mondo e una gamma completa di servizi HR. Offre soluzioni di Temporary, Permanent e Professional Staffing pensate per le esigenze di piccole e medie imprese, aziende corporate e multinazionali per le quali il Gruppo ha sviluppato uno specifico know how. <\/div>\n              <div class=\"brand_card_button\"><a href=\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/temporary-permanent-e-professional-staffing\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" viewBox=\"0 0 80 80\"><g id=\"Oval\" fill=\"none\" stroke=\"#96b9ff\" stroke-miterlimit=\"10\" stroke-width=\"1\"><circle cx=\"40\" cy=\"40\" r=\"40\" stroke=\"none\"\/><circle cx=\"40\" cy=\"40\" r=\"39.5\" fill=\"none\"\/><\/g><path id=\"Combined_Shape\" data-name=\"Combined Shape\" d=\"M15.935,18.635a1.271,1.271,0,0,1-.1-1.642l.1-.118,5.944-6.132H1.206a1.247,1.247,0,0,1-.14-2.48l.14-.009H21.882L15.935,2.124a1.273,1.273,0,0,1-.1-1.643l.1-.117a1.179,1.179,0,0,1,1.592-.1l.113.1,7.991,8.241A1.26,1.26,0,0,1,26,9.5a1.281,1.281,0,0,1-.031.282h0l0,.021,0,.008,0,.015,0,.014,0,.009-.006.021v0a1.247,1.247,0,0,1-.2.389l0,0a1.241,1.241,0,0,1-.109.125l-7.993,8.243a1.18,1.18,0,0,1-1.705,0Z\" transform=\"translate(27 32)\" fill=\"#96b9ff\"\/><\/svg><\/a><\/div>\n            <\/div>\n          <\/div>\n                        <\/div>\n    <\/div>\n    <script>\n      jQuery(document).ready(function($) {\n        function owlInitialize() {\n            if ($(window).width() < 1025) {\n                $('#brand_cards .row').addClass(\"owl-carousel\");\n                $('#brand_cards .owl-carousel').owlCarousel({\n                    loop:false,    \n                    margin: 20,  \n                    nav: false,\n                    dots: true,        \n                    responsive:{\n                        0:{\n                            items:1,           \n                        },\n                        640:{\n                            items:1,           \n                        }, \n                    }\n                });\n            }else{\n                $('.owl-carousel').owlCarousel('destroy');\n                $('#brand_cards .row').removeClass(\"owl-carousel\");\n            }\n        }\n      \n        owlInitialize();\n\n        jQuery(window).resize(function() {\n          owlInitialize();\n        });\n      });\n    <\/script>\n    <style>\n      @media(max-width: 1024px) {\n        #brand_cards {\n          padding-bottom: 80px;\n        }\n        #brand_cards .owl-dots {\n          display: flex;\n          justify-content: center;\n          margin-top: 40px;\n        }\n        #brand_cards .owl-stage-outer {\n          overflow: visible;\n        }\n        #brand_cards .brand_card_holder {\n          overflow-y: auto;\n        }\n        #brand_cards .brand_card_inner {\n          margin: 0 15px;\n        }\n        #brand_cards .brand_card_holder {\n          border-radius: 8px;\n        }\n        #brand_cards .brand_card_content {\n          height: 190px;\n          overflow: hidden;\n          margin-bottom: 30px;\n        }\n        .brand_card_thumb img {\n          height: 65px;\n          object-fit: contain;\n        }\n        #brand_cards .owl-dot {\n          width: 12px;\n          height: 12px;\n          background-color: #ECE9F1;\n          margin: 0px 5px;\n          border-style: none;\n        }\n        #brand_cards .owl-dot.active {\n          width: 12px;\n          height: 12px;\n          background-color: #005AFF;\n        }\n        #brand_cards .brand_card_inner {\n          width: 100%;\n        }\n      }\n      @media(min-width: 769px) and (max-width: 1024px) {\n        #brand_cards .brand_card_content {\n          height: 110px;\n        }\n      }\n    <\/style>\n  <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gi Group \u00e8 la prima agenzia per il lavoro italiana con oltre 500 filiali nel mondo e una gamma completa di servizi HR. Offre soluzioni di Temporary, Permanent e Professional Staffing pensate per le esigenze di piccole e medie imprese, aziende corporate e multinazionali per le quali il Gruppo ha sviluppato uno specifico know how. <\/p>\n","protected":false},"featured_media":16846,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"country":[],"class_list":["post-159","one-group","type-one-group","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una propostaHR completa<\/title>\n<meta name=\"description\" content=\"Siamo la pi\u00f9 grande agenzia per il lavoro italiana presente su tutto il territorio nazionale con oltre 200 filiali (oltre 500 in tutto il mondo) e una gamma completa di servizi HR.Il nostro DNA italiano ci permette di essere flessibili, creativi e trovare le soluzioni pi\u00f9 adatte in tempi rapidi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gi Group Holding - Temporary, Permanent &amp;Professional Staffing\" \/>\n<meta property=\"og:description\" content=\"L&#039;attivit\u00e0 di Temporary, Permanent e Professional Staffing \u00e8 il core business del Gruppo, ed \u00e8 portata avanti attraverso il brand Gi Group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/\" \/>\n<meta property=\"og:site_name\" content=\"Gi Group Holding Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T09:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gi Group Holding - Temporary, Permanent &amp;Professional Staffing\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;attivit\u00e0 di Temporary, Permanent e Professional Staffing \u00e8 il core business del Gruppo, ed \u00e8 portata avanti attraverso il brand Gi Group.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/\",\"name\":\"Una propostaHR completa\",\"isPartOf\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png\",\"datePublished\":\"2021-12-28T15:12:24+00:00\",\"dateModified\":\"2026-05-05T09:16:03+00:00\",\"description\":\"Siamo la pi\u00f9 grande agenzia per il lavoro italiana presente su tutto il territorio nazionale con oltre 200 filiali (oltre 500 in tutto il mondo) e una gamma completa di servizi HR.Il nostro DNA italiano ci permette di essere flessibili, creativi e trovare le soluzioni pi\u00f9 adatte in tempi rapidi.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png\",\"contentUrl\":\"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png\",\"width\":3622,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Il Gruppo\",\"item\":\"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporary, Permanent e Professional Staffing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gigroupholding.com\/italia\/#website\",\"url\":\"https:\/\/www.gigroupholding.com\/italia\/\",\"name\":\"Gi Group Holding Italia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gigroupholding.com\/italia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una propostaHR completa","description":"Siamo la pi\u00f9 grande agenzia per il lavoro italiana presente su tutto il territorio nazionale con oltre 200 filiali (oltre 500 in tutto il mondo) e una gamma completa di servizi HR.Il nostro DNA italiano ci permette di essere flessibili, creativi e trovare le soluzioni pi\u00f9 adatte in tempi rapidi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/","og_locale":"it_IT","og_type":"article","og_title":"Gi Group Holding - Temporary, Permanent &Professional Staffing","og_description":"L'attivit\u00e0 di Temporary, Permanent e Professional Staffing \u00e8 il core business del Gruppo, ed \u00e8 portata avanti attraverso il brand Gi Group.","og_url":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/","og_site_name":"Gi Group Holding Italia","article_modified_time":"2026-05-05T09:16:03+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Gi Group Holding - Temporary, Permanent &Professional Staffing","twitter_description":"L'attivit\u00e0 di Temporary, Permanent e Professional Staffing \u00e8 il core business del Gruppo, ed \u00e8 portata avanti attraverso il brand Gi Group.","twitter_image":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2022\/04\/Featured-Image-social-media-1.png","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/","url":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/","name":"Una propostaHR completa","isPartOf":{"@id":"https:\/\/www.gigroupholding.com\/italia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage"},"image":{"@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png","datePublished":"2021-12-28T15:12:24+00:00","dateModified":"2026-05-05T09:16:03+00:00","description":"Siamo la pi\u00f9 grande agenzia per il lavoro italiana presente su tutto il territorio nazionale con oltre 200 filiali (oltre 500 in tutto il mondo) e una gamma completa di servizi HR.Il nostro DNA italiano ci permette di essere flessibili, creativi e trovare le soluzioni pi\u00f9 adatte in tempi rapidi.","breadcrumb":{"@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#primaryimage","url":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png","contentUrl":"https:\/\/www.gigroupholding.com\/italia\/wp-content\/uploads\/sites\/2\/2021\/12\/Gi-Group-_-Logo-Positive.png","width":3622,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/www.gigroupholding.com\/italia\/one-group\/temporary-permanent-e-professional-staffing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Il Gruppo","item":"https:\/\/www.gigroupholding.com\/italia\/il-gruppo\/"},{"@type":"ListItem","position":2,"name":"Temporary, Permanent e Professional Staffing"}]},{"@type":"WebSite","@id":"https:\/\/www.gigroupholding.com\/italia\/#website","url":"https:\/\/www.gigroupholding.com\/italia\/","name":"Gi Group Holding Italia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gigroupholding.com\/italia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group"}],"about":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/types\/one-group"}],"version-history":[{"count":120,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/159\/revisions"}],"predecessor-version":[{"id":16874,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/one-group\/159\/revisions\/16874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/media\/16846"}],"wp:attachment":[{"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/media?parent=159"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.gigroupholding.com\/italia\/wp-json\/wp\/v2\/country?post=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}