{"id":9039,"date":"2023-08-04T15:00:32","date_gmt":"2023-08-04T15:00:32","guid":{"rendered":"https:\/\/www.gigroupholding.com\/brasil\/gi-group-adquire-stato-uma-das-principais-consultorias-em-outplacement-do-brasil-2\/"},"modified":"2023-08-04T18:11:49","modified_gmt":"2023-08-04T18:11:49","slug":"futuro-do-trabalho-tecnologia","status":"publish","type":"post","link":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/","title":{"rendered":"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9039\" class=\"elementor elementor-9039\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c36dd0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c36dd0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f12c85b\" data-id=\"f12c85b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-325f1e0 elementor-widget elementor-widget-heading\" data-id=\"325f1e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Not\u00edcias -  <b>Futuro do Trabalho e Tecnologia<\/b><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a2e239 elementor-widget elementor-widget-spacer\" data-id=\"0a2e239\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3753c41 elementor-widget elementor-widget-heading\" data-id=\"3753c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fa8726 elementor-widget elementor-widget-spacer\" data-id=\"0fa8726\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"unlimited-elements-background-overlay\" data-forid=\"c36dd0d\" data-location=\"back\" style=\"display:none\">\n\t\t\t<template>\n\t\t\t<!-- start Header Background --> <style>#uc_header_background_bg_addon17963{grid-template-columns:8% 40% 45% 7%;grid-template-rows:[row1-start] 15% [row1-end row2-start] auto [row2-end row3-start] 180px [row3-end]}#uc_header_background_bg_addon17963{grid-template-columns:7% 40% 45% 8%}#uc_header_background_bg_addon17963 .grid_block.grid_n2{border-left:25px solid}#uc_header_background_bg_addon17963 .grid_block.grid_n6{border-left:25px solid;border-bottom:25px solid;border-bottom-left-radius:3vw}#uc_header_background_bg_addon17963 .grid_block.grid_n11{border-top:25px solid;border-right:25px solid;border-top-right-radius:3vw;margin-top:-25px}@media(max-width:768px){#uc_header_background_bg_addon17963{grid-template-columns:5% 25% 60% 10%;grid-template-rows:[row1-start] 15% [row1-end row2-start] auto [row2-end row3-start] 100px [row3-end]}#uc_header_background_bg_addon17963 .grid_block.grid_n2{border-left:16px solid}#uc_header_background_bg_addon17963 .grid_block.grid_n6{border-left:16px solid;border-bottom:16px solid;border-bottom-left-radius:13vw}#uc_header_background_bg_addon17963 .grid_block.grid_n11{border-top:16px solid;border-right:16px solid;border-top-right-radius:13vw;margin-top:-16px}}<\/style> <div id=\"uc_header_background_bg_addon17963\" class=\"header_bg d-grid w-100 h-100\"><div class=\"grid_block grid_n1\"><\/div><div class=\"grid_block grid_n2\"><\/div><div class=\"grid_block grid_n3\"><\/div><div class=\"grid_block grid_n4\"><\/div><div class=\"grid_block grid_n5\"><\/div><div class=\"grid_block grid_n6\"><\/div><div class=\"grid_block grid_n7\"><\/div><div class=\"grid_block grid_n8\"><\/div><div class=\"grid_block grid_n9\"><\/div><div class=\"grid_block grid_n10\"><\/div><div class=\"grid_block grid_n11\"><\/div><div class=\"grid_block grid_n12\"><\/div><\/div> <script type=\"text\/javascript\"  id=\"ue_script_header_background\">\n\n\/* Header Background scripts: *\/ \n\n\n<\/script> <!-- end Header Background -->\t\t\t<\/template>\n\t\t<\/div>\n\t\t\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-161586f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"161586f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53a299f\" data-id=\"53a299f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdfbadf elementor-widget elementor-widget-heading\" data-id=\"bdfbadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">S\u00e3o Paulo, 04 de Agosto de 2023<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-effacd6 elementor-widget elementor-widget-text-editor\" data-id=\"effacd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-9723\" src=\"https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2023\/08\/profissional-tecnologia-futuro-do-trabalho-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2023\/08\/profissional-tecnologia-futuro-do-trabalho-300x200.jpg 300w, https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2023\/08\/profissional-tecnologia-futuro-do-trabalho-1024x683.jpg 1024w, https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2023\/08\/profissional-tecnologia-futuro-do-trabalho-768x512.jpg 768w, https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2023\/08\/profissional-tecnologia-futuro-do-trabalho-1536x1025.jpg 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><em>Executivos da Gi Group Holding explicam que o Brasil enfrenta dois cen\u00e1rios destoantes: um por exig\u00eancias de profissionais qualificados e outro pela quest\u00e3o educacional do Brasil, que ainda reflete muitas desigualdades.<\/em><\/p><p>A for\u00e7a de trabalho vem sendo automatizada mais r\u00e1pido do que o esperado. Segundo o relat\u00f3rio Future of Jobs Report 2023, big data, computa\u00e7\u00e3o em nuvem e Intelig\u00eancia Artificial est\u00e3o no topo da lista de tecnologias que cerca de 75% das empresas buscar\u00e3o adotar at\u00e9 2027.<\/p><p>E j\u00e1 faz ao menos uma d\u00e9cada que muitos estudos apontavam que viver\u00edamos um gap de talentos no mercado, n\u00e3o pela extin\u00e7\u00e3o de postos de trabalho que seriam substitu\u00eddos pela tecnologia, mas pela falta de profissionais com as habilidades e compet\u00eancias necess\u00e1rias para atuar em um modelo de trabalho fortemente pautado pelas tecnologias digitais.<\/p><p><strong>Discutir o tema e pensar em estrat\u00e9gias \u00e9 essencial para ambos os lados<\/strong><\/p><p>Preparar empresas e profissionais para essa mudan\u00e7a que j\u00e1 est\u00e1 acontecendo \u00e9 fundamental. Por isso, a Gi Group Holding, como ecossistema completo de recursos humanos, tem debatido o tema em eventos e materiais. Em maio, foi realizado o evento Future of Work, com a presen\u00e7a de gestores da holding do Brasil e Reino Unido e de participantes de grandes empresas dispostos a discutir sobre essa necessidade de adapta\u00e7\u00e3o.<\/p><p>Irina Bezzan, diretora da The Bridge, unidade de rede de talentos tech &amp; digital da Gi Group Holding, destacou: \u201cPara permanecer na \u00e1rea, era e \u00e9 necess\u00e1rio desenvolver muito as hard skills, fundamentais para a inova\u00e7\u00e3o. Contudo, o que faz um bom ambiente de trabalho s\u00e3o tamb\u00e9m as soft skills. Costumamos dizer que, na tecnologia, temos muitas pessoas \u00f3timas em hard skills mas que precisam desenvolver bastante as soft skills. E isso, acredito, \u00e9 um dos pontos mais dif\u00edceis para atrair talentos na \u00e1rea: \u00e9 por isso que o treinamento e desenvolvimento s\u00e3o fundamentais para preencher esse gap na tecnologia\u201d.<\/p><p>Dados do relat\u00f3rio Tend\u00eancias Globais de RH no setor de Manufatura \u2013 2023, tamb\u00e9m realizado pela holding, revelou que a Ind\u00fastria 4.0 j\u00e1 vem enfrentando essa lacuna nas contrata\u00e7\u00f5es, com impactos diretos na gera\u00e7\u00e3o de resultados e sustentabilidade da estrat\u00e9gia das empresas. De acordo com o levantamento da multinacional, 88% das empresas brasileiras do setor consultadas relatam ter dificuldades de encontrar trabalhadores qualificados, \u00edndice superior \u00e0 m\u00e9dia global, que ficou em 66%. <\/p><p>De acordo com Renato Soares, diretor da Tack TMI, divis\u00e3o de treinamento e desenvolvimento, a velocidade das mudan\u00e7as que est\u00e3o acontecendo em diversos segmentos, que no caso da Manufatura s\u00e3o refletidos nesse modelo de ind\u00fastria 4.0, \u00e9 maior do que o tempo de rea\u00e7\u00e3o da sociedade para uma a\u00e7\u00e3o efetiva na forma\u00e7\u00e3o de profissionais preparados a essas novas exig\u00eancias. <\/p><p>Isso ocorre porque a dimens\u00e3o da mudan\u00e7a das compet\u00eancias e habilidades exigidas dos profissionais n\u00e3o se refere somente a conhecimentos t\u00e9cnicos em tecnologias digitais, por exemplo. Acontece tamb\u00e9m porque essas transforma\u00e7\u00f5es est\u00e3o exigindo abordagens diferentes de trabalho, novos modelos mentais. \u201cHoje, temos entregado treinamentos para lideran\u00e7as que falam sobre Mindset Digital, tomando decis\u00f5es baseadas em dados, e outros conte\u00fados que indicam que a natureza do trabalho de muitas fun\u00e7\u00f5es est\u00e1 em transforma\u00e7\u00e3o\u201d, destaca o executivo.<\/p><p><strong>E o que o empres\u00e1rio pode fazer para reter profissionais e prepar\u00e1-los para exercer uma fun\u00e7\u00e3o?<\/strong><\/p><p>Esse cen\u00e1rio traz uma complexidade de solu\u00e7\u00f5es. \u201cPensando naquilo que est\u00e1 ao alcance das organiza\u00e7\u00f5es para se fazer de forma mais imediata, realizar a integra\u00e7\u00e3o das informa\u00e7\u00f5es de uma consistente abordagem de gest\u00e3o de talentos que ajude a identificar claramente caracter\u00edsticas dos indiv\u00edduos que aceleram sua capacidade de aprendizado e adapta\u00e7\u00e3o, vinculados a um mapeamento de habilidades e compet\u00eancias cr\u00edticas que permitam a constru\u00e7\u00e3o de programa de treinamento tanto de soft skills quanto de hard skills, acabam sendo as a\u00e7\u00f5es mais efetivas para gerir os riscos de uma aus\u00eancia de profissionais qualificados que impactam diretamente a gera\u00e7\u00e3o de resultados\u201d, afirma.<\/p><p>Para Soares, a pesquisa refor\u00e7a que, apesar de diferentes habilidades, as exig\u00eancias tanto para n\u00edvel operacional quanto para gest\u00e3o refletem essas transforma\u00e7\u00f5es.<\/p><p>\u201cNossa pesquisa sobre tend\u00eancias de RH para Manufatura mostra que, enquanto profissionais de n\u00edveis operacionais est\u00e3o demandado em conhecimentos t\u00e9cnicos especializados em m\u00e1quinas e ferramentas com alto n\u00edvel de tecnologia integrada, al\u00e9m de digital skills e conhecimento sobre tecnologia de f\u00e1bricas inteligentes; para os n\u00edveis de gest\u00e3o, capacidade anal\u00edtica, capacidade de gerenciar projetos al\u00e9m de habilidades digitais s\u00e3o exemplos de habilidades mais demandadas\u201d.<\/p><p>Ele lembra que o fato de termos amplo acesso \u00e0 informa\u00e7\u00e3o e conhecimento n\u00e3o garante que as pessoas \u201cautomaticamente\u201d conseguir\u00e3o se preparar para esses desafios. \u201cO volume de informa\u00e7\u00f5es que temos acesso hoje traz o desafio de saber identificar quais s\u00e3o relevantes para o desenvolvimento profissional. \u00c9 importante que ajudemos as pessoas a pensar em suas carreiras, em suas necessidades e ajud\u00e1-las a encontrar formas de selecionar aqueles conhecimentos mais cr\u00edticos para si mesmos e para as empresas nas quais trabalham. Programas consistentes de gest\u00e3o de talentos devem ajudar seus potenciais a encontrar caminhos para se pensar as melhores trilhas para forma\u00e7\u00e3o. Ajudar n\u00e3o significa tutorar, dizer o que as pessoas precisam fazer como \u201creceitas de bolo\u201d, mas precisam trazer dados sobre tend\u00eancias, estrat\u00e9gia do neg\u00f3cio, desafios e ajudar a detalhar como essas vari\u00e1veis impactam no conjunto de habilidades e compet\u00eancias exigidos\u201d, ressalta Soares.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c66e8ee elementor-widget elementor-widget-spacer\" data-id=\"c66e8ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A for\u00e7a de trabalho vem sendo automatizada mais r\u00e1pido do que o esperado. Pensando nisso, como profissionais e empresas devem se preparar para os desafios impostos pela transforma\u00e7\u00e3o digital? Leia neste artigo!<\/p>\n","protected":false},"author":48,"featured_media":8772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[],"class_list":["post-9039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial - Gi Group Holding Brasil<\/title>\n<meta name=\"description\" content=\"The New Corporate Brand Represents The Company&#039;s Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gi Group Holding Brasil - Gi Group announces a landmark moment in its company&#039;s history - the launch of Gi Group Holding\" \/>\n<meta property=\"og:description\" content=\"The New Corporate Brand Represents The Company&#039;s Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Gi Group Holding Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-04T15:00:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-04T18:11:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2022\/04\/Featured-Image-social-media.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"fsilva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gi Group Holding Brasil - Gi Group announces a landmark moment in its company&#039;s history - the launch of Gi Group Holding\" \/>\n<meta name=\"twitter:description\" content=\"The New Corporate Brand Represents The Company&#039;s Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn.gigroupholding.com\/sites\/3\/2022\/04\/Featured-Image-social-media.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fsilva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/\"},\"author\":{\"name\":\"fsilva\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/#\\\/schema\\\/person\\\/4f9c94c273982ca5a8315c5ca30c4c1f\"},\"headline\":\"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial\",\"datePublished\":\"2023-08-04T15:00:32+00:00\",\"dateModified\":\"2023-08-04T18:11:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/\"},\"wordCount\":1009,\"image\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.gigroupholding.com\\\/sites\\\/3\\\/2021\\\/12\\\/Visual2.jpg\",\"articleSection\":[\"Neg\u00f3cio\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/\",\"url\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/\",\"name\":\"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial - Gi Group Holding Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.gigroupholding.com\\\/sites\\\/3\\\/2021\\\/12\\\/Visual2.jpg\",\"datePublished\":\"2023-08-04T15:00:32+00:00\",\"dateModified\":\"2023-08-04T18:11:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/#\\\/schema\\\/person\\\/4f9c94c273982ca5a8315c5ca30c4c1f\"},\"description\":\"The New Corporate Brand Represents The Company's Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.gigroupholding.com\\\/sites\\\/3\\\/2021\\\/12\\\/Visual2.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.gigroupholding.com\\\/sites\\\/3\\\/2021\\\/12\\\/Visual2.jpg\",\"width\":1600,\"height\":837},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/futuro-do-trabalho-tecnologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Neg\u00f3cio\",\"item\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/category\\\/negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/#website\",\"url\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/\",\"name\":\"Gi Group Holding Brasil\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/#\\\/schema\\\/person\\\/4f9c94c273982ca5a8315c5ca30c4c1f\",\"name\":\"fsilva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g\",\"caption\":\"fsilva\"},\"url\":\"https:\\\/\\\/www.gigroupholding.com\\\/brasil\\\/author\\\/fsilva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial - Gi Group Holding Brasil","description":"The New Corporate Brand Represents The Company's Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/","og_locale":"pt_BR","og_type":"article","og_title":"Gi Group Holding Brasil - Gi Group announces a landmark moment in its company's history - the launch of Gi Group Holding","og_description":"The New Corporate Brand Represents The Company's Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.","og_url":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/","og_site_name":"Gi Group Holding Brasil","article_published_time":"2023-08-04T15:00:32+00:00","article_modified_time":"2023-08-04T18:11:49+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.gigroupholding.com\/brasil\/wp-content\/uploads\/sites\/3\/2022\/04\/Featured-Image-social-media.png","type":"image\/png"}],"author":"fsilva","twitter_card":"summary_large_image","twitter_title":"Gi Group Holding Brasil - Gi Group announces a landmark moment in its company's history - the launch of Gi Group Holding","twitter_description":"The New Corporate Brand Represents The Company's Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.","twitter_image":"https:\/\/cdn.gigroupholding.com\/sites\/3\/2022\/04\/Featured-Image-social-media.png","twitter_misc":{"Escrito por":"fsilva","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#article","isPartOf":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/"},"author":{"name":"fsilva","@id":"https:\/\/www.gigroupholding.com\/brasil\/#\/schema\/person\/4f9c94c273982ca5a8315c5ca30c4c1f"},"headline":"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial","datePublished":"2023-08-04T15:00:32+00:00","dateModified":"2023-08-04T18:11:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/"},"wordCount":1009,"image":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.gigroupholding.com\/sites\/3\/2021\/12\/Visual2.jpg","articleSection":["Neg\u00f3cio"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/","url":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/","name":"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial - Gi Group Holding Brasil","isPartOf":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#primaryimage"},"image":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.gigroupholding.com\/sites\/3\/2021\/12\/Visual2.jpg","datePublished":"2023-08-04T15:00:32+00:00","dateModified":"2023-08-04T18:11:49+00:00","author":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/#\/schema\/person\/4f9c94c273982ca5a8315c5ca30c4c1f"},"description":"The New Corporate Brand Represents The Company's Global, Multi-Brand Staffing And Recruitment Business Ecosystem With A Footprint In 30 Countries.","breadcrumb":{"@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#primaryimage","url":"https:\/\/cdn.gigroupholding.com\/sites\/3\/2021\/12\/Visual2.jpg","contentUrl":"https:\/\/cdn.gigroupholding.com\/sites\/3\/2021\/12\/Visual2.jpg","width":1600,"height":837},{"@type":"BreadcrumbList","@id":"https:\/\/www.gigroupholding.com\/brasil\/futuro-do-trabalho-tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Neg\u00f3cio","item":"https:\/\/www.gigroupholding.com\/brasil\/category\/negocio\/"},{"@type":"ListItem","position":2,"name":"Futuro do trabalho: os impactos da transforma\u00e7\u00e3o digital nos profissionais, na gest\u00e3o de talentos e na estrat\u00e9gia empresarial"}]},{"@type":"WebSite","@id":"https:\/\/www.gigroupholding.com\/brasil\/#website","url":"https:\/\/www.gigroupholding.com\/brasil\/","name":"Gi Group Holding Brasil","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gigroupholding.com\/brasil\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.gigroupholding.com\/brasil\/#\/schema\/person\/4f9c94c273982ca5a8315c5ca30c4c1f","name":"fsilva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9de2d96ad7047d8915c0356d5345bd90a589c0e2aa224065e12b9a996c70a6a0?s=96&d=mm&r=g","caption":"fsilva"},"url":"https:\/\/www.gigroupholding.com\/brasil\/author\/fsilva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/posts\/9039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/comments?post=9039"}],"version-history":[{"count":9,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/posts\/9039\/revisions"}],"predecessor-version":[{"id":9732,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/posts\/9039\/revisions\/9732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/media\/8772"}],"wp:attachment":[{"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/media?parent=9039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/categories?post=9039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gigroupholding.com\/brasil\/wp-json\/wp\/v2\/tags?post=9039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}